{"id":1869,"date":"2022-06-17T12:41:42","date_gmt":"2022-06-17T10:41:42","guid":{"rendered":"https:\/\/costacopenhagen.com\/?page_id=1869"},"modified":"2025-04-30T11:46:37","modified_gmt":"2025-04-30T09:46:37","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/costacopenhagen.com\/da\/aviso-legal\/","title":{"rendered":"Aviso Legal"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1869\" class=\"elementor elementor-1869\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fde5e3d elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"fde5e3d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec29b59\" data-id=\"ec29b59\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35aeeb5 elementor-widget elementor-widget-icon-box\" data-id=\"35aeeb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h1 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAVISO LEGAL Y CONDICIONES GENERALES DE USO\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h1>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f3d055 elementor-widget elementor-widget-text-editor\" data-id=\"1f3d055\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u00a01. <\/strong><strong>INFORMACI\u00d3N GENERAL<\/strong><\/p><p>En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y el Comercio Electr\u00f3nico (LSSI-CE) de 11 de julio, se facilitan a continuaci\u00f3n los siguientes datos de informaci\u00f3n general de este sitio web:<\/p><p><strong>Identidad:<\/strong> Edeling Estates S.L. con CIF B 93736676 en adelante \u201cel Titular\u201d<\/p><p><strong>Direcci\u00f3n:<\/strong> C\/Adelfas de Campo Mijas 1; 29649; MIJAS &#8211; M\u00c1LAGA<\/p><p><strong>Tel\u00e9fono:<\/strong> 616 151035<\/p><p><strong>E-mail:<\/strong> <a href=\"mailto:birgitte@costacopenhagen.com\"><span style=\"color: #000000;\">birgitte@costacopenhagen.com<\/span><\/a><\/p><p>La empresa se encuentra inscrita en el Registro Mercantil de T 5920, L 4827, F 139, S 8, H MA154738<\/p><p><strong>2. T\u00c9RMINOS Y CONDICIONES GENERALES DE USO<\/strong><\/p><p><strong>El objeto de las condiciones: El Sitio Web<\/strong><\/p><p>El objeto de las presentes Condiciones Generales de Uso (en adelante, Condiciones) es regular el acceso y la utilizaci\u00f3n del Sitio Web. A los efectos de las presentes Condiciones se entender\u00e1 como Sitio Web: la apariencia externa de los interfaces de pantalla, tanto de forma est\u00e1tica como de forma din\u00e1mica, es decir, el \u00e1rbol de navegaci\u00f3n; y todos los elementos integrados tanto en los interfaces de pantalla como en el \u00e1rbol de navegaci\u00f3n (en adelante, Contenidos) y todos aquellos servicios o recursos en l\u00ednea que en su caso ofrezca a los Usuarios (en adelante, Servicios).<\/p><p>El Titular se reserva la facultad de modificar, en cualquier momento, y sin aviso previo, la presentaci\u00f3n y configuraci\u00f3n del Sitio Web y de los Contenidos y Servicios que en \u00e9l pudieran estar incorporados. El Usuario reconoce y acepta que en cualquier momento el Titular pueda interrumpir, desactivar y\/o cancelar cualquiera de estos elementos que se integran en el Sitio Web o el acceso a los mismos.<\/p><p>El acceso al Sitio Web por el Usuario tiene car\u00e1cter libre y, por regla general, es gratuito sin que el Usuario tenga que proporcionar una contraprestaci\u00f3n para poder disfrutar de ello, salvo en lo relativo al coste de conexi\u00f3n a trav\u00e9s de la red de telecomunicaciones suministrada por el proveedor de acceso que hubiere contratado el Usuario.<\/p><p>La utilizaci\u00f3n de alguno de los Contenidos o Servicios del Sitio Web podr\u00e1 hacerse mediante la suscripci\u00f3n o registro previo del Usuario.<\/p><p><strong>El Usuario<\/strong><\/p><p>El acceso, la navegaci\u00f3n y uso del Sitio Web confiere la condici\u00f3n de Usuario, por lo que se aceptan, desde que se inicia la navegaci\u00f3n por el Sitio Web, todas las Condiciones aqu\u00ed establecidas, as\u00ed como sus ulteriores modificaciones, sin perjuicio de la aplicaci\u00f3n de la correspondiente normativa legal de obligado cumplimiento seg\u00fan el caso. Dada la relevancia de lo anterior, se recomienda al Usuario leerlas cada vez que visite el Sitio Web.<\/p><p>El Sitio Web del Titular proporciona gran diversidad de informaci\u00f3n, servicios y datos. El Usuario asume su responsabilidad para realizar un uso correcto del Sitio Web. Esta responsabilidad se extender\u00e1 a:<\/p><ul><li>Un uso de la informaci\u00f3n, Contenidos y\/o Servicios y datos ofrecidos por el Titular sin que sea contrario a lo dispuesto por las presentes Condiciones, la Ley, la moral o el orden p\u00fablico, o que de cualquier otro modo puedan suponer lesi\u00f3n de los derechos de terceros o del mismo funcionamiento del Sitio Web.<\/li><li>La veracidad y licitud de las informaciones aportadas por el Usuario en los formularios extendidos por el Titular para el acceso a ciertos Contenidos o Servicios ofrecidos por el Sitio Web. En todo caso, el Usuario notificar\u00e1 de forma inmediata al Titular acerca de cualquier hecho que permita el uso indebido de la informaci\u00f3n registrada en dichos formularios, tales como, pero no s\u00f3lo, el robo, extrav\u00edo, o el acceso no autorizado a identificadores y\/o contrase\u00f1as, con el fin de proceder a su inmediata cancelaci\u00f3n.<\/li><\/ul><p>El mero acceso a este Sitio Web no supone entablar ning\u00fan tipo de relaci\u00f3n de car\u00e1cter comercial entre el Titular y el Usuario.<\/p><p>El Usuario declara ser mayor de edad y disponer de la capacidad jur\u00eddica suficiente para vincularse por las presentes Condiciones. Por lo tanto, este Sitio Web del Titular no se dirige a menores de edad. El Titular declina cualquier responsabilidad por el incumplimiento de este requisito.<\/p><p><strong>3. ACCESO Y NAVEGACI\u00d3N EN EL SITIO WEB: EXCLUSI\u00d3N DE GARANT\u00cdAS Y RESPONSABILIDAD<\/strong><\/p><p>El Titular no garantiza la continuidad, disponibilidad y utilidad del Sitio Web, ni de los Contenidos o Servicios. El Titular har\u00e1 todo lo posible por el buen funcionamiento del Sitio Web, sin embargo, no se responsabiliza ni garantiza que el acceso a este Sitio Web no vaya a ser ininterrumpido o que est\u00e9 libre de error.<\/p><p>Tampoco se responsabiliza o garantiza que el contenido o software al que pueda accederse a trav\u00e9s de este Sitio Web est\u00e9 libre de error o cause un da\u00f1o al sistema inform\u00e1tico (software y hardware) del Usuario. En ning\u00fan caso el Titular ser\u00e1 responsable por las p\u00e9rdidas, da\u00f1os o perjuicios de cualquier tipo que surjan por el acceso, navegaci\u00f3n y el uso del Sitio Web, incluy\u00e9ndose, pero no limit\u00e1ndose, a los ocasionados a los sistemas inform\u00e1ticos o los provocados por la introducci\u00f3n de virus.<\/p><p>El Titular tampoco se hace responsable de los da\u00f1os que pudiesen ocasionarse a los usuarios por un uso inadecuado de este Sitio Web. En particular, no se hace responsable en modo alguno de las ca\u00eddas, interrupciones, falta o defecto de las telecomunicaciones que pudieran ocurrir.<\/p><p><strong>4. POL\u00cdTICA DE ENLACES<\/strong><\/p><p>Se informa que el Sitio Web del Titular pone o puede poner a disposici\u00f3n de los Usuarios medios de enlace (como, entre otros, links, banners, botones), directorios y motores de b\u00fasqueda que permiten a los Usuarios acceder a sitios web pertenecientes y\/o gestionados por terceros.<\/p><p>La instalaci\u00f3n de estos enlaces, directorios y motores de b\u00fasqueda en el Sitio Web tiene por objeto facilitar a los Usuarios la b\u00fasqueda de y acceso a la informaci\u00f3n disponible en Internet, sin que pueda considerarse una sugerencia, recomendaci\u00f3n o invitaci\u00f3n para la visita de los mismos.<\/p><p>El Titular no ofrece ni comercializa por s\u00ed ni por medio de terceros los productos y\/o servicios disponibles en dichos sitios enlazados.<\/p><p>Asimismo, tampoco garantizar\u00e1 la disponibilidad t\u00e9cnica, exactitud, veracidad, validez o legalidad de sitios ajenos a su propiedad a los que se pueda acceder por medio de los enlaces.<\/p><p>El Titular en ning\u00fan caso revisar\u00e1 o controlar\u00e1 el contenido de otros sitios web, as\u00ed como tampoco aprueba, examina ni hace propios los productos y servicios, contenidos, archivos y cualquier otro material existente en los referidos sitios enlazados.<\/p><p>El Titular no asume ninguna responsabilidad por los da\u00f1os y perjuicios que pudieran producirse por el acceso, uso, calidad o licitud de los contenidos, comunicaciones, opiniones, productos y servicios de los sitios web no gestionados por el Titular y que sean enlazados en este Sitio Web.<\/p><p>El Usuario o tercero que realice un hiperv\u00ednculo desde una p\u00e1gina web de otro, distinto, sitio web al Sitio Web del Titular deber\u00e1 saber que:<\/p><ul><li>No se permite la reproducci\u00f3n \u2014total o parcialmente\u2014 de ninguno de los Contenidos y\/o Servicios del Sitio Web sin autorizaci\u00f3n expresa del Titular<\/li><li>No se permite tampoco ninguna manifestaci\u00f3n falsa, inexacta o incorrecta sobre el Sitio Web del Titular, ni sobre los Contenidos y\/o servicios del mismo.<\/li><\/ul><p>A excepci\u00f3n del hiperv\u00ednculo, el sitio web en el que se establezca dicho hiperenlace no contendr\u00e1 ning\u00fan elemento, de este Sitio Web, protegido como propiedad intelectual por el ordenamiento jur\u00eddico espa\u00f1ol, salvo autorizaci\u00f3n expresa del Titular.<\/p><p>El establecimiento del hiperv\u00ednculo no implicar\u00e1 la existencia de relaciones entre el Titular y el titular del sitio web desde el cual se realice, ni el conocimiento y aceptaci\u00f3n del Titular de los contenidos, servicios y\/o actividades ofrecidos en dicho sitio web, y viceversa.<\/p><p><strong>5. COMUNICACIONES COMERCIALES POR V\u00cdA ELECTR\u00d3NICA<\/strong><\/p><p><strong>\u00a0<\/strong><\/p><p>Previo consentimiento otorgado por el Usuario, remitiremos informaci\u00f3n sobre nuestros productos y\/o servicios. El env\u00edo de dichas comunicaciones comerciales sobre actividades, servicios, ofertas, promociones especiales, etc. podr\u00e1 efectuarse por cualquier medio, incluyendo correo electr\u00f3nico.<\/p><p>El Titular no remite comunicaciones comerciales por v\u00eda electr\u00f3nica sin identificarlas como tales conforme a lo dispuesto en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y de comercio electr\u00f3nico.<\/p><p>El Usuario puede oponerse al tratamiento de sus datos con fines promocionales mediante el env\u00edo de un correo electr\u00f3nico a la direcci\u00f3n indicada en el punto 1 quedando revocado su consentimiento, en cualquier momento, simplemente notificando su voluntad de revocarlo. No ser\u00e1 considerado como comunicaci\u00f3n comercial la informaci\u00f3n que se env\u00ede cuya finalidad sea la del mantenimiento de la relaci\u00f3n contractual existente entre el Usuario y el Titular; as\u00ed como el desempe\u00f1o de tareas de informaci\u00f3n y otras actividades propias del servicio que el Usuario pudiera contratar con la empresa.<\/p><p><strong>6. PROPIEDAD INTELECTUAL E INDUSTRIAL<\/strong><\/p><p>El Titular por s\u00ed o como parte cesionaria, es titular de todos los derechos de propiedad intelectual e industrial del Sitio Web, as\u00ed como de los elementos contenidos en el mismo (a t\u00edtulo enunciativo y no exhaustivo, im\u00e1genes, sonido, audio, v\u00eddeo, software o textos, marcas o logotipos, combinaciones de colores, estructura y dise\u00f1o, selecci\u00f3n de materiales usados, programas de ordenador necesarios para su funcionamiento, acceso y uso, etc.). Ser\u00e1n, por consiguiente, obras protegidas como propiedad intelectual por el ordenamiento jur\u00eddico espa\u00f1ol, si\u00e9ndoles aplicables tanto la normativa espa\u00f1ola y comunitaria en este campo, como los tratados internacionales relativos a la materia y suscritos por Espa\u00f1a.<\/p><p>Todos los derechos reservados. En virtud de lo dispuesto en la Ley de Propiedad Intelectual, quedan expresamente prohibidas la reproducci\u00f3n, la distribuci\u00f3n y la comunicaci\u00f3n p\u00fablica, incluida su modalidad de puesta a disposici\u00f3n, de la totalidad o parte de los contenidos de esta p\u00e1gina web, con fines comerciales, en cualquier soporte y por cualquier medio t\u00e9cnico, sin la autorizaci\u00f3n del Titular<\/p><p>El Usuario se compromete a respetar los derechos de propiedad intelectual e industrial del Titular. Podr\u00e1 visualizar los elementos del Sitio Web o incluso imprimirlos, copiarlos y almacenarlos en el disco duro de su ordenador o en cualquier otro soporte f\u00edsico siempre y cuando sea, exclusivamente, para su uso personal. El Usuario, sin embargo, no podr\u00e1 suprimir, alterar, o manipular cualquier dispositivo de protecci\u00f3n o sistema de seguridad que estuviera instalado en el Sitio Web.<\/p><p>En caso de que el Usuario o tercero considere que cualquiera de los Contenidos del Sitio Web suponga una violaci\u00f3n de los derechos de protecci\u00f3n de la propiedad intelectual, deber\u00e1 comunicarlo inmediatamente al Titular a trav\u00e9s de los datos de contacto del apartado N.\u00ba 1 INFORMACI\u00d3N GENERAL de este Aviso Legal y Condiciones Generales de Uso.<\/p><p><strong>7. ACCIONES LEGALES, LEGISLACI\u00d3N APLICABLE Y JURISDICCI\u00d3N<\/strong><\/p><p>El Titular se reserva la facultad de presentar las acciones civiles o penales que considere necesarias por la utilizaci\u00f3n indebida del Sitio Web y Contenidos, o por el incumplimiento de las presentes Condiciones.<\/p><p>La relaci\u00f3n entre el Usuario y el Titular se regir\u00e1 por la normativa vigente y de aplicaci\u00f3n en el territorio espa\u00f1ol. De surgir cualquier controversia en relaci\u00f3n con la interpretaci\u00f3n y\/o a la aplicaci\u00f3n de estas Condiciones las partes someter\u00e1n sus conflictos a la jurisdicci\u00f3n ordinaria someti\u00e9ndose a los Juzgados y tribunales que correspondan conforme a derecho.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4bfc67e elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"4bfc67e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ecea94f\" data-id=\"ecea94f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c615bac elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c615bac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h1 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tT\u00e9rminos, Condiciones y Aviso Legal\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h1>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5baa4ce elementor-widget elementor-widget-text-editor\" data-id=\"5baa4ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El hecho de acceder a este sitio web () implica el conocimiento y aceptaci\u00f3n de los siguientes t\u00e9rminos y condiciones de uso.<\/p><p>El Usuario se compromete a utilizar la p\u00e1gina web de conformidad con la ley y el presente Aviso Legal, as\u00ed como con la moral y las buenas costumbres generalmente aceptadas y el orden p\u00fablico.<\/p><p>Lea atentamente los apartados que constan a continuaci\u00f3n. Se trata de toda la informaci\u00f3n legal necesaria que usted debe conocer para navegar con seguridad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c24f9bf elementor-widget elementor-widget-text-editor\" data-id=\"c24f9bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>1. Informaci\u00f3n general del titular de la web.<\/h2><p>A los efectos del art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de la Ley de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico, se informa al Usuario que el Titular de la p\u00e1gina web es:<\/p><p>\u00a0con NIF\u00a0<\/p><p><strong>Datos de contacto:<\/strong><br \/><strong>Direcci\u00f3n postal<\/strong>:\u00a0<br \/><strong>Tel\u00e9fono<\/strong>:\u00a0<br \/><strong>E-mail<\/strong>:\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b175c8 elementor-widget elementor-widget-text-editor\" data-id=\"8b175c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>2. Propiedad intelectual e industrial.<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0c75d9 elementor-widget elementor-widget-text-editor\" data-id=\"f0c75d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>2.1 Contenidos.<\/h4><p>Todos los elementos que integran el dise\u00f1o gr\u00e1fico de esta web, los men\u00fas, botones de navegaci\u00f3n, el c\u00f3digo fuente, los textos, im\u00e1genes, fotograf\u00edas, texturas, gr\u00e1ficos, animaciones, v\u00eddeos y cualquier otro contenido son propiedad de Lauren keri Miller.<\/p><p>Del mismo modo, Lauren keri Miller tambi\u00e9n es titular de las marcas, signos distintivos, nombres de dominio y nombres comerciales (excepto los correspondientes a patrocinadores, sponsor, anunciantes, etc.), que aparecieran en el presente sitio web.<\/p><p>As\u00ed, quedan reservados todos los derechos de reproducci\u00f3n total o parcial, modificaci\u00f3n, adaptaci\u00f3n, comunicaci\u00f3n p\u00fablica, tratamiento inform\u00e1tico, distribuci\u00f3n, transformaci\u00f3n, cesi\u00f3n, venta, alquiler, pr\u00e9stamo y\/o cualquier otro derecho de propiedad intelectual o industrial que pueda corresponder al Titular sobre los contenidos de la p\u00e1gina web. Cualquier ejercicio de los anteriores derechos estar\u00e1 sujeto a autorizaci\u00f3n previa y por escrito del titular de los mismos.<\/p><p>El Titular se compromete a corregir, tan pronto como tenga conocimiento de ello, los posibles errores formales o num\u00e9ricos que puedan encontrarse a lo largo del contenido de las distintas secciones de la web.<\/p><p>El acceso al presente sitio web no supone, en ning\u00fan caso, la adquisici\u00f3n por parte de los usuarios de derecho de propiedad alguno sobre los contenidos que figuran en el mismo, por lo que no podr\u00e1n ser utilizados con ninguna finalidad. La utilizaci\u00f3n indebida de estos contenidos por parte del Usuario le har\u00e1 responsable \u00fanico frente al Titular y frente a terceros, de los da\u00f1os ocasionados, as\u00ed como de los incumplimientos legales que pudieran derivarse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bbd242 elementor-widget elementor-widget-text-editor\" data-id=\"9bbd242\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>2.2 Enlaces.<\/h4><p>Se informa que la presencia de enlaces a p\u00e1ginas web gestionadas por terceros en este sitio web es meramente informativa y no constituye en ning\u00fan caso una invitaci\u00f3n a la contrataci\u00f3n de productos o servicios que se ofrezcan en el sitio web de destino. El acceso por parte del Usuario ser\u00e1 bajo su exclusiva responsabilidad y en las condiciones de uso que rijan en los mismos.<\/p><p>En caso de tener conocimiento efectivo de que la informaci\u00f3n o la actividad a la que se remite desde dichos enlaces es il\u00edcita, constitutiva de delito o puede lesionar bienes o derechos de un tercero susceptibles de indemnizaci\u00f3n, el Titular actuar\u00e1 con la diligencia necesaria para suprimir o inutilizar el enlace correspondiente con la mayor brevedad posible.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c3d568 elementor-widget elementor-widget-text-editor\" data-id=\"9c3d568\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>3. Comunicaciones comerciales por v\u00eda electr\u00f3nica.<\/h2><p>Al dejarnos sus datos de contacto, el Usuario otorga su consentimiento para recibir informaci\u00f3n sobre nuestros servicios. El env\u00edo de dichas comunicaciones comerciales sobre actividades, servicios, ofertas, promociones especiales, etc. podr\u00e1 efectuarse por cualquier medio, incluyendo correo electr\u00f3nico.<\/p><p>El Titular no remite comunicaciones comerciales por v\u00eda electr\u00f3nica sin identificarlas como tales conforme a lo dispuesto en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y de comercio electr\u00f3nico.<\/p><p>El Usuario puede oponerse al tratamiento de sus datos con fines promocionales mediante el env\u00edo de un correo electr\u00f3nico a la direcci\u00f3n <a href=\"mailto:info@costacopenhagen.redlinecompany-hosting.com\">info@costacopenhagen.redlinecompany-hosting.com<\/a> quedando revocado su consentimiento, en cualquier momento, simplemente notificando su voluntad de revocarlo.<\/p><p>No ser\u00e1 considerado como comunicaci\u00f3n comercial la informaci\u00f3n que se env\u00ede cuya finalidad sea la del mantenimiento de la relaci\u00f3n contractual existente entre el Usuario y el Titular; as\u00ed como el desempe\u00f1o de tareas de informaci\u00f3n y otras actividades propias del servicio que el Usuario pudiera contratar con la empresa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1da6dfa elementor-widget elementor-widget-text-editor\" data-id=\"1da6dfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>4. Pol\u00edtica de cookies.<\/h2><p>La presente p\u00e1gina web utiliza cookies. Una cookie es un fichero que se descarga en su ordenador al acceder a determinadas p\u00e1ginas web. Las cookies permiten a una p\u00e1gina web, entre otras cosas, almacenar y recuperar informaci\u00f3n sobre los h\u00e1bitos de navegaci\u00f3n de un usuario o de su equipo y, dependiendo de la informaci\u00f3n que contengan y de la forma en que utilice su equipo, pueden utilizarse para reconocer al usuario.<\/p><p>Puede obtener m\u00e1s informaci\u00f3n sobre las cookies utilizadas en esta p\u00e1gina web consultando el apartado <a href=\"https:\/\/costacopenhagen.com\/da\/cookie-policy\/\">POL\u00cdTICA DE COOKIES<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26d077c elementor-widget elementor-widget-text-editor\" data-id=\"26d077c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>5. Limitaciones o exclusiones de responsabilidad.<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f51aa42 elementor-widget elementor-widget-text-editor\" data-id=\"f51aa42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>5.1 Fallos t\u00e9cnicos.<\/h4><p>El Titular no puede garantizar la disponibilidad y continuidad del funcionamiento de la web y que no ser\u00e1 en ning\u00fan caso responsable por cualesquiera da\u00f1os y perjuicios que puedan derivarse de esa falta de accesibilidad al sitio web, fallos inform\u00e1ticos, aver\u00edas telef\u00f3nicas, desconexiones, retrasos o bloqueos causados por deficiencias o sobrecargas en las l\u00edneas telef\u00f3nicas, en el sistema de Internet o en otros sistemas electr\u00f3nicos producidos en el curso del funcionamiento, y otros da\u00f1os que puedan ser causados por terceras personas mediante intromisiones no autorizadas ajenas al control del titular de la web.<\/p><p>El Titular utiliza programas de detecci\u00f3n de virus para controlar todos los contenidos que se introducen en el sitio web. No obstante, no se podr\u00e1 garantizar la ausencia de virus ni de otros elementos introducidos por terceros ajenos que puedan producir alteraciones en los sistemas f\u00edsicos o l\u00f3gicos de los usuarios o en los documentos electr\u00f3nicos y ficheros almacenados en sus sistemas.<\/p><p>En todo caso, se exime al Titular de cualesquiera da\u00f1os y perjuicios derivados de los mismos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65db3fa elementor-widget elementor-widget-text-editor\" data-id=\"65db3fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>5.2 Responsabilidad por contenidos.<\/h4><p>El Titular se reserva el derecho de interrumpir el acceso a su p\u00e1gina o a cualquiera de sus contenidos en cualquier momento y sin previo aviso, y no se responsabiliza de los perjuicios que pueda sufrir el usuario por los errores u omisiones de los que pudieran adolecer los contenidos de la web, si bien se compromete a verificar y vigilar peri\u00f3dicamente los contenidos e informaciones del mismo.<\/p><p>El Titular garantiza que todos los contenidos y servicios que se ofrecen en esta web respetan el principio de dignidad de la persona, el principio de no-discriminaci\u00f3n por motivos de raza, sexo, religi\u00f3n, opini\u00f3n, nacionalidad, discapacidad o cualquier otra circunstancia personal y social, as\u00ed como el principio de protecci\u00f3n de la juventud y de la infancia.<\/p><p>El Titular no se har\u00e1 responsable de otros contenidos alojados por terceros en su p\u00e1gina web cuando no se tenga conocimiento efectivo de que dicha informaci\u00f3n almacenada es il\u00edcita o de que lesiona bienes o derechos de un tercero susceptibles de indemnizaci\u00f3n, o si se tiene tal conocimiento, que se act\u00fae con diligencia para retirar los citados contenidos o hacer imposible el acceso a ellos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-433d348 elementor-widget elementor-widget-text-editor\" data-id=\"433d348\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>6. Acciones legales, legislaci\u00f3n aplicable y jurisdicci\u00f3n.<\/h2><p>El Titular se reserva la facultad de presentar las acciones civiles o penales que considere necesarias por la utilizaci\u00f3n indebida del Sitio Web y Contenidos, o por el incumplimiento de las presentes Condiciones.<\/p><p>La relaci\u00f3n entre el Usuario y El Titular se regir\u00e1 por la normativa vigente y de aplicaci\u00f3n en el territorio espa\u00f1ol. De surgir cualquier controversia en relaci\u00f3n con la interpretaci\u00f3n y\/o a la aplicaci\u00f3n de estas Condiciones las partes someter\u00e1n sus conflictos a la jurisdicci\u00f3n ordinaria someti\u00e9ndose a los Juzgados y tribunales que correspondan conforme a derecho.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>AVISO LEGAL Y CONDICIONES GENERALES DE USO \u00a01. INFORMACI\u00d3N GENERAL En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y el Comercio Electr\u00f3nico (LSSI-CE) de 11 de julio, se facilitan a continuaci\u00f3n los siguientes datos de informaci\u00f3n general de este sitio web: Identidad: Edeling [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1869","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/costacopenhagen.com\/da\/wp-json\/wp\/v2\/pages\/1869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costacopenhagen.com\/da\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/costacopenhagen.com\/da\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/costacopenhagen.com\/da\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/costacopenhagen.com\/da\/wp-json\/wp\/v2\/comments?post=1869"}],"version-history":[{"count":7,"href":"https:\/\/costacopenhagen.com\/da\/wp-json\/wp\/v2\/pages\/1869\/revisions"}],"predecessor-version":[{"id":9020,"href":"https:\/\/costacopenhagen.com\/da\/wp-json\/wp\/v2\/pages\/1869\/revisions\/9020"}],"wp:attachment":[{"href":"https:\/\/costacopenhagen.com\/da\/wp-json\/wp\/v2\/media?parent=1869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}